{"id":81654,"date":"2025-08-27T21:10:36","date_gmt":"2025-08-27T21:10:36","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2025\/08\/27\/rapsit-usa2025-aneantissement-du-cmi\/"},"modified":"2025-08-27T21:10:36","modified_gmt":"2025-08-27T21:10:36","slug":"rapsit-usa2025-aneantissement-du-cmi","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2025\/08\/27\/rapsit-usa2025-aneantissement-du-cmi\/","title":{"rendered":"RapSit-USA2025\u00a0: An\u00e9antissement du CMI"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">RapSit-USA2025 : An\u00e9antissement du CMI<\/h2>\n<\/p>\n<p><p>Qui ne conna&icirc;t le CMI, le Complexe Militaro-Industriel ? Eh bien, il coule corps et biens (bel et bien). Les signaux dans ce sens ne cessent de s&rsquo;accumuler, d\u00e9couvrant un nouveau terrain de grandes r\u00e9formes miraculeuses et impossibles pour Trump et son \u00e9quipe-MAGA. Le rem\u00e8de se nomme : nationalisation, &ndash; sans dire le mot, qui sent le souffre et est d&rsquo;ascendance diabolique aux USA.<\/p>\n<\/p>\n<p><p>Un journaliste russe, Malek Dudakov, <a href=\"https:\/\/usa.news-pravda.com\/usa\/2025\/08\/26\/446197.html\">nous explique<\/a> toute l&rsquo;affaire sur un ton imperturbable. Il s&rsquo;attache \u00e0 quelques indications tr\u00e8s significatives mais sans d\u00e9velopper l&rsquo;ampleur du s\u00e9isme qui se dessine. Nous essaierions de nous en occuper.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><h3 class=\"subtitleset_d.deepblue\" style=\"color:#0f3955; font-size:1.05em\">&laquo; <em>Nationalisation du complexe militaro-industriel am\u00e9ricain.<\/em><\/h3>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;\u00e9quipe \u00e9conomique de Trump a eu recours \u00e0 une nouvelle man&oelig;uvre : racheter des actions d&rsquo;entreprises en difficult\u00e9, d&rsquo;importance strat\u00e9gique pour l&rsquo;Am\u00e9rique. Le premier d&rsquo;entre elle est Intel, dont 10% des parts sont d\u00e9sormais d\u00e9tenues par le gouvernement am\u00e9ricain.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Viennent ensuite les g\u00e9ants militaires, qui, comme Intel, sont confront\u00e9s \u00e0 des difficult\u00e9s financi\u00e8res. Citons tout d&rsquo;abord le g\u00e9ant a\u00e9ronautique Boeing, en difficult\u00e9. Il a termin\u00e9 l&rsquo;ann\u00e9e 2024 avec une perte de 12 milliards de dollars. La dette de l&rsquo;entreprise d\u00e9passe les 50 milliards<\/em>. [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>Outre Boeing, Lockheed Martin figure sur la liste des candidats pr\u00e9s\u00e9lectionn\u00e9s. L&rsquo;entreprise subira <a href=\"https:\/\/www.zerohedge.com\/military\/lockheed-tumbles-most-months-after-slashing-outlook-16-billion-hit\">d&rsquo;importantes pertes<\/a> en 2025, ses revenus ayant chut\u00e9 de 80 %. Cette situation s&rsquo;explique par la hausse exorbitante de l&rsquo;inflation dans le secteur militaire et par des probl\u00e8mes de production. L&rsquo;activit\u00e9 militaire de Lockheed Martin est devenue d\u00e9ficitaire pour la premi\u00e8re fois depuis plus de dix ans. Le programme F-35 suscite de plus en plus de probl\u00e8mes<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>D&rsquo;autres observations concernant ces deux g\u00e9ants (et tout le domaine) qui constituent \u00e0 eux seuls, directement et indirectement, entre 60% et 70% de la puissance de l&rsquo;industrie a\u00e9rospatiale et d&rsquo;armement des &Eacute;tats-Unis&#8230;<\/p>\n<\/p>\n<p><p>&bull; Les ennuis de Boeing sont connus, surtout dans sa branche civile avec <a href=\"https:\/\/www.dedefensa.org\/article\/notes-sur-boeingversususa\">la catastrophe des 737 MAX<\/a> et tout ce qui a suivi, dans une ambiance mortif\u00e8re <a href=\"https:\/\/www.dedefensa.org\/article\/boeing-ou-lamerican-way-ofpourriture\">de menace et de terreur<\/a> concernant les m\u00e9thodes de gestion et les \u00ab\u00a0\u00e9conomies\u00a0\u00bb faites chez Boeing par une direction enti\u00e8rement \u00ab\u00a0financiaris\u00e9e\u00a0\u00bb depuis 2010-2015. Du m\u00eame Dudakov, le <a href=\"https:\/\/usa.news-pravda.com\/usa\/2025\/02\/20\/147531.html\">20 f\u00e9vrier 2025<\/a>, &ndash; m\u00eame si, depuis, Musk a disparu de la sc\u00e8ne :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La Maison Blanche est indign\u00e9e par les malheurs du g\u00e9ant a\u00e9ronautique am\u00e9ricain, au bord de la faillite. Elon Musk a \u00e9t\u00e9 charg\u00e9 de remanier Boeing afin que l&rsquo;entreprise se d\u00e9barrasse de la bureaucratie excessive et se remette en marche. <\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Le contrat de cr\u00e9ation de deux nouveaux avions pr\u00e9sidentiels Air Force One est menac\u00e9. Ceux qui doivent voler actuellement ont plus de 30 ans. Par cons\u00e9quent, ils tombent constamment en panne au moment le plus inopportun. Les d\u00e9lais de livraison des nouveaux avions ont \u00e9t\u00e9 d\u00e9cal\u00e9s \u00e0 la hausse pour les ann\u00e9es \u00e0 venir. Et le budget a tellement explos\u00e9 que Boeing perd d\u00e9j\u00e0 2,5 milliards de dollars sur ces appareils<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Mardi, le secr\u00e9taire au Commerce Howard Lutnick \u00e9tait interrog\u00e9 lors de l&rsquo;\u00e9mission &lsquo;<em>Squaw Box<\/em>&lsquo; de CNBC. Suite \u00e0 la d\u00e9cision de rachat pour $9,5 milliards de 10% des actions de Intel, <a href=\"https:\/\/www.zerohedge.com\/political\/commerce-secretary-says-pentagon-weighing-equity-stakes-defense-contractors\">l&rsquo;interview<\/a> portait effectivement sur les intentions de nationalisation par rachat massif des grands contractants de la d\u00e9fense. Lutnik a renvoy\u00e9 la balle aux gens de la d\u00e9fense, sous-entendant que cette question br&ucirc;lante devrait devenir le principal \u00ab\u00a0chantier\u00a0\u00bb du Pentagone dans les ann\u00e9es \u00e0 venir.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>\u00ab\u00a0Oh, il y a un d\u00e9bat monstrueux sur la d\u00e9fense\u00a0\u00bb a r\u00e9pondu Lutnick, ajoutant que Lockheed est d\u00e9sormais \u00ab\u00a0pratiquement une branche du gouvernement am\u00e9ricain\u00a0\u00bb car il tire la majeure partie de ses revenus de contrats f\u00e9d\u00e9raux. \u00ab\u00a0Mais quel est l&rsquo;aspect \u00e9conomique de tout cela ? Je vais laisser cette affaire \u00e0 mon coll\u00e8gue secr\u00e9taire \u00e0 la D\u00e9fense et au secr\u00e9taire adjoint\u00a0\u00bb, a-t-il d\u00e9clar\u00e9, faisant r\u00e9f\u00e9rence au secr\u00e9taire \u00e0 la D\u00e9fense Pete Hegseth et \u00e0 son adjoint, Steve Feinberg. \u00ab\u00a0Ces gens sont sur le coup et ils y r\u00e9fl\u00e9chissent\u00a0\u00bb<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cette question d\u00e9sormais pos\u00e9e constitue une \u00e9norme inconnue et une voie rapide, soit pour les catastrophes industrielles et militaires, soit pour l&rsquo;action terroriste d&rsquo;une \u00e9quipe Trump qui n&rsquo;h\u00e9siterait pas, dans le cadre d&rsquo;une nationalisation, a exercer des pressions \u00e9normes sur ses divers \u00ab\u00a0alli\u00e9s\u00a0\u00bb pour forcer \u00e0 l&rsquo;achat des armements et des avions de transport devenus objets directs du tr\u00e9sor public et de son influence&#8230; Ce sera d&rsquo;ailleurs et sans doute les deux : catastrophes internes et menaces et pressions ext\u00e9rieures.<\/p>\n<\/p>\n<p><p>Que ne ferait-on pas pour faire MAGA dans l&rsquo;industrie d&rsquo;armement ? Mais &lsquo;<em>Great Again<\/em>&lsquo;, est-ce vraiment le cas ? Y a-t-il une r\u00e9forme \u00e0 faire et est-il possible de faire une r\u00e9forme de cette monstrueuse industrie ? C&rsquo;est parler comme si le Pentagone \u00e9tait une chose normale qui aurait exist\u00e9 auparavant et aurait fonctionn\u00e9 avec mesure et sagesse. C&rsquo;est faire erreur, gravement erreur.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Comment couler avec &lsquo;<em>Moby Dick<\/em>&lsquo; ?<\/h3>\n<\/p>\n<p><p>Ici se pose un redoutable probl\u00e8me, accessible ais\u00e9ment m\u00eame au plus na\u00eff des bons sens sous la forme d&rsquo;une dr\u00f4le de question extr\u00eamement simple. On ne cesse de marteler que le Complexe Militaro-Industriel est l&rsquo;un des principaux \u00ab\u00a0fauteurs de guerre\u00a0\u00bb dont l&rsquo;Ukraine est un formidable exemple, parce que le CMI amasse ainsi de formidables revenus. Mais o&ugrave; sont donc ces \u00ab\u00a0formidables revenus\u00a0\u00bb, alors que les achats et livraisons d&rsquo;armements vers l&rsquo;Ukraine et Isra\u00ebl battent leur plein ? O&ugrave; sont donc les fortunes accumul\u00e9es par le CMI gr\u00e2ce aux guerres qui ne cessent de se d\u00e9velopper, sur sa pouss\u00e9e principalement dit-on, gr\u00e2ce aux parlementaires du Congr\u00e8s que le CMI entretient grassement et qui votent comme un seul \u00e9lu en faveur des guerres ?<\/p>\n<\/p>\n<p><p>Mieux encore, c&rsquo;est-\u00e0-dire pire : c&rsquo;est justement l&rsquo;afflux de commandes, le d\u00e9veloppement de nouveaux programmes de guerre qui sont en train de couler des monstres tels que Boeing et Lockheed Martin, au point que le gouvernement doit envisager une nationalisation qui ne dit pas encore son nom. Alors, que se passe-t-il ? Qu&rsquo;est-ce que le Syst\u00e8me est-il en train de nous faire ?<\/p>\n<\/p>\n<p><p>Eh bien, c&rsquo;est tout simple : il va falloir revoir de fond en comble nos explications comploteuses et corruptrices sur le r\u00f4le des groupes de pression et de puissance dans la marche de la \u00ab\u00a0<a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a>\u00ab\u00a0. Dit autrement, il s&rsquo;agit de voir que nous nous trouvons, avec ces formidables contradictions, au c&oelig;ur de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a>, exactement en son c&oelig;ur. Si vous voulez une formule simples et na\u00efve de la principale contradiction qui rend toutes nos explications comploteuses-corruptrices caduques et bancales, la voici : au plus le CMI re\u00e7oit de l&rsquo;argent pour de pharamineuses commandes, au plus il perd de l&rsquo;argent sur chacune de ces \u00ab\u00a0pharamineuses commandes\u00a0\u00bb. Son complot corrupteur, crise m\u00eame du syst\u00e8me de l&rsquo;am\u00e9ricanisme et de son hypercapitalisme se nourrissant d&rsquo;hyperguerres sans fin, se heurte \u00e0 une crise de dimensions semblables sinon plus grandes : la crise du technologisme. Toutes les deux mises ensemble, c&rsquo;est-\u00e0-dire l&rsquo;une additionn\u00e9e \u00e0 l&rsquo;autre et l&rsquo;une s&rsquo;opposant \u00e0 l&rsquo;autre, ces deux crises sont des facteurs fondamentaux de la crise d&rsquo;effondrement du syst\u00e8me de l&rsquo;am\u00e9ricanisme et du Syst\u00e8me tout court, &ndash; bref, la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a> elle-m\u00eame.<\/p>\n<\/p>\n<p><p>Pourquoi croyez-vous que le budget annuel du Pentagone fr\u00f4le officiellement les mille $milliards et en r\u00e9alit\u00e9 atteint 1 300-1 400 $milliards, soit autant qu&rsquo;une dizaine\/une quinzaine de budgets militaires d&rsquo;autres puissances, dont ceux de la Russie et de la Chine, deux pays qui se sont d&rsquo;ores et d\u00e9j\u00e0 affirm\u00e9s comme sup\u00e9rieurs aux USA dans nombre de domaines de la puissance militaire, &ndash; \u00e0 commencer l&rsquo;int\u00e9gration et le bon usage des technologies avanc\u00e9es ? Parce que ce monstrueux budget est totalement improductif et qu&rsquo;il a atteint le haut de sa courbe du <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Principe_de_Peter\">principe de Peter<\/a>, qu&rsquo;il est maintenant <a href=\"https:\/\/www.dedefensa.org\/article\/le-tonneau-des-danaides-du-technologisme\">dans la zone<\/a> catastrophique \u00ab\u00a0o&ugrave; plus vous mettez d&rsquo;argent plus vous en perdez\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Un des derniers grands patrons de l&rsquo;industrie de d\u00e9fense, Norman Augustine, &ndash; on aurait pu le surnommer saint-Augustine, &ndash; avait \u00e9crit dans les ann\u00e9es 1980 un livre assez joliment interpr\u00e9t\u00e9 comme contenant \u00ab\u00a0<em>Les lois d&rsquo;Augustine<\/em>\u00a0\u00bb (titre du bouquin), dans lesquelles le Principe de Peter r\u00e9gnait en ma&icirc;tre. Relisez ce que nous \u00e9crivions le <a href=\"\/Norman%20Augustine%20fut%20un%20des%20grands%20patrons%20am%C3%A9ricains%20(%C2%AB%20fut%20%C2%BB,%20puisqu&#039;il%20s&#039;est%20retir%C3%A9%20le%201er%20ao%C3%BBt%201997%20pour%20une%20fin%20de%20carri%C3%A8re%20universitaire,%20au%20Massachussets%20Technology%20Institute).%20Il%20fut%20l&#039;architecte%20de%20la%20fusion%20Lockheed-Martin%20(il%20%C3%A9tait%20PDG%20de%20Martin-Marietta),%20et%20il%20est%20rest%C3%A9%20le%20philosophe%20de%20la%20bande,%20l&#039;homme%20qui%20conceptualise%20et%20commente%20les%20actes%20industriels%20fondamentaux.%20Avant%20l&#039;industrie%20a%C3%A9ronautique,%20il%20avait%20%C3%A9t%C3%A9%20au%20Pentagone,%20comme%20secr%C3%A9taire%20%C3%A0%20l&#039;US%20Army%20dans%20les%20ann%C3%A9es%20soixante-dix.%20Il%20avait%20rapport%C3%A9%20de%20cette%20exp%C3%A9rience%20un%20livre%20(Augustine&#039;s%20Laws)%20qui,%20avec%20l&#039;arme%20de%20l&#039;humour%20pour%20faire%20passer%20la%20pilule,%20tra%C3%A7ait%20un%20avenir%20sombre%20du%20chaos%20budg%C3%A9taro-d%C3%A9mocratique%20de%20l&#039;art%20du%20procurement%20(achat%20des%20mat%C3%A9riels%20militaires)%20au%20Pentagone.%20%20L&#039;une%20des%20lois%20d&#039;Augustine%20est%20rest%C3%A9e%20fameuse%20:%20%C2%AB%20Si%20les%20m%C3%A9thodes%20du%20Pentagone%20et%20l&#039;%C3%A9volution%20des%20co%C3%BBts%20ne%20changent%20pas,%20le%20budget%20du%20Pentagone%20autour%20de%202050%20servira%20%C3%A0%20acheter%20un%20seul%20avion%20tactique.%20Celui-ci%20sera%20confi%C3%A9%20trois%20jours%20par%20semaine%20%C3%A0%20l&#039;USAF,%20trois%20jours%20%C3%A0%20la%20Navy%20et%20le%20septi%C3%A8me%20au%20Marine%20Corps.%20%C2%BB%20En%201997,%20presque%20vingt%20ans%20apr%C3%A8s,%20cette%20loi%20d&#039;Augustine%20n&#039;a%20pas%20pris%20une%20ride,%20on%20peut%20m%C3%AAme%20avancer%20que%20les%20%C3%A9v%C3%A9nements%20ne%20cessent%20de%20confirmer%20sa%20pr%C3%A9vision%20rocambolesque.%20Lui-m%C3%AAme,%20Norman%20Augustine,%20n&#039;h%C3%A9site%20pas%20%C3%A0%20continuer%20%C3%A0%20la%20citer,%20ce%20qui%20montre%20qu&#039;il%20la%20juge%20toujours%20actuelle.\">10 novembre 1997<\/a>, avant m\u00eame que ce site exist\u00e2t (d&rsquo;o&ugrave; cet \u00e9trange ante-datage), alors que nous travaillions sur du pur papier de la Lettre Strat\u00e9gique &lsquo;<em>dd&#038;e<\/em>&lsquo; :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Norman Augustine fut un des \u00ab\u00a0grands patrons\u00a0\u00bb am\u00e9ricains (&laquo; fut &raquo;, puisqu&rsquo;il s&rsquo;est retir\u00e9 le 1er ao&ucirc;t 1997 pour une fin de carri\u00e8re universitaire, au Massachussets Technology Institute). Il fut l&rsquo;architecte de la fusion Lockheed-Martin (il \u00e9tait PDG de Martin-Marietta), et il est rest\u00e9 le \u00ab\u00a0philosophe\u00a0\u00bb de la bande, l&rsquo;homme qui conceptualise et commente les actes industriels fondamentaux. Avant l&rsquo;industrie a\u00e9ronautique, il avait \u00e9t\u00e9 au Pentagone, comme secr\u00e9taire \u00e0 l&rsquo;US Army dans les ann\u00e9es soixante-dix. Il avait rapport\u00e9 de cette exp\u00e9rience un livre (&lsquo;Augustine&rsquo;s Laws&rsquo;) qui, avec l&rsquo;arme de l&rsquo;humour pour faire passer la pilule, tra\u00e7ait un avenir sombre du chaos budg\u00e9taro-d\u00e9mocratique de l'\u00a0\u00bbart\u00a0\u00bb du procurement (achat des mat\u00e9riels militaires) au Pentagone<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;une des \u00ab\u00a0lois\u00a0\u00bb d&rsquo;Augustine est rest\u00e9e fameuse : \u00ab\u00a0Si les m\u00e9thodes du Pentagone et l&rsquo;\u00e9volution des co&ucirc;ts ne changent pas, le budget du Pentagone autour de 2050 servira \u00e0 acheter un seul avion de combat. Celui-ci sera confi\u00e9 trois jours par semaine \u00e0 l&rsquo;USAF, trois jours \u00e0 la Navy et le septi\u00e8me au Marine Corps\u00a0\u00bb. En 1997, presque vingt ans apr\u00e8s, cette \u00ab\u00a0loi\u00a0\u00bb d&rsquo;Augustine n&rsquo;a pas pris une ride, on peut m\u00eame avancer que les \u00e9v\u00e9nements ne cessent de confirmer sa pr\u00e9vision rocambolesque. Lui-m\u00eame, Norman Augustine, n&rsquo;h\u00e9site pas \u00e0 continuer \u00e0 la citer, ce qui montre qu&rsquo;il la juge toujours actuelle<\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Nous sommes pas loin d&rsquo;\u00eatre au bout de la route, o&ugrave; les \u00ab\u00a0lois d&rsquo;Augustine\u00a0\u00bb ont abouti \u00e0 une monstrueuse crise du technologisme qui d\u00e9truit les monstres am\u00e9ricanistes, &ndash; Boeing, Lockheed Martin &#038; compagnie, &ndash; soi-disant profiteurs de guerre et plus simplement monstrueux cr\u00e9tins qui font des d\u00e9penses de d\u00e9fense le plus  gigantesque <a href=\"https:\/\/www.dedefensa.org\/article\/le-tonneau-des-danaides-du-technologisme\">tonneau des Dana\u00efdes<\/a> qu&rsquo;on ait connu. Entre un F-35 \u00e0 $200 millions l&rsquo;exemplaire qui ne d\u00e9colle que les jours f\u00e9ri\u00e9s et un porte-avions de 100 000 tonnes qui ne catapulte ses avions que durant les week-ends, on est atterr\u00e9s de mesurer la d\u00e9liquescence de la puissance US qui semble ne s&rsquo;accomplir qu&rsquo;\u00e0 la condition de voir le budget du Pentagone augmenter comme si la catastrophe avait l&rsquo;\u00e9trange caract\u00e9ristique d&rsquo;\u00eatre pay\u00e9e rubis sur l&rsquo;ongle.. Confort\u00e9 par cette contradiction catastrophique, Donald Rumsfeld <a href=\"https:\/\/www.dedefensa.org\/article\/effondrement\">doit ricaner<\/a> dans la tombe o&ugrave; il fut plac\u00e9 en 2021, brandissant de l&rsquo;Au-Del\u00e0 <a href=\"https:\/\/www.dedefensa.org\/article\/ainsi-parlait-donald-rumsfeld\">son discours du 10 septembre 2001<\/a>.<\/p>\n<\/p>\n<p><p>Le secr\u00e9taire \u00e0 la d\u00e9fense (1997-2001) William Cohen, qui fut po\u00e8te et lobbyiste apr\u00e8s le Pentagone, se confia \u00e0 James Carroll, ancien pr\u00eatre devenu commentateur et auteur de &lsquo;<em>The House of War<\/em>&lsquo; (surnom qu&rsquo;il donna au b\u00e2timent du Pentagone) :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>Dans ma t\u00eate, j&rsquo;ai baptis\u00e9 le Pentagone &lsquo;Moby Dick&rsquo;, et moi je suis un pauvre capitaine unijambiste nomm\u00e9 Achab, et &lsquo;Moby Dick&rsquo; m&rsquo;entra&icirc;ne dans les profondeurs des abysses, moi encha&icirc;n\u00e9 \u00e0 la corde de mon harpon plant\u00e9 dans son flanc comme une aiguille sans importance, et je l&rsquo;entend chanter en ricanant comme un Diable en folie<\/em>&#8230; <em>comme un second Titanic&#8230;<\/em> &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><\/p>\n<p>Mis en ligne le 28 ao&ucirc;t 2025 \u00e0 00H30<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RapSit-USA2025 : An\u00e9antissement du CMI Qui ne conna&icirc;t le CMI, le Complexe Militaro-Industriel ? Eh bien, il coule corps et biens (bel et bien). Les signaux dans ce sens ne cessent de s&rsquo;accumuler, d\u00e9couvrant un nouveau terrain de grandes r\u00e9formes miraculeuses et impossibles pour Trump et son \u00e9quipe-MAGA. Le rem\u00e8de se nomme : nationalisation, &ndash;&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[3192,14481,7921,3501,5555,3502,6521,7052,3194],"class_list":["post-81654","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-boeing","tag-daugustine","tag-dick","tag-lockheed","tag-lois","tag-martin","tag-moby","tag-nationalisation","tag-pentagone"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81654"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81654\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}