{"id":81668,"date":"2025-09-09T16:26:21","date_gmt":"2025-09-09T16:26:21","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2025\/09\/09\/le-torrent-irrefragable-de-la-grandecrise\/"},"modified":"2025-09-09T16:26:21","modified_gmt":"2025-09-09T16:26:21","slug":"le-torrent-irrefragable-de-la-grandecrise","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2025\/09\/09\/le-torrent-irrefragable-de-la-grandecrise\/","title":{"rendered":"Le torrent irr\u00e9fragable de la GrandeCrise"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>Le torrent irr\u00e9fragable de la GrandeCrise<\/strong><\/h2>\n<\/p>\n<p><p>9  septembre 2025 (16H20) &ndash; Je parle de la <a href=\"https:\/\/www.dedefensa.org\/article\/glossairedde-la-gces\">GrandeCrise<\/a>, on le sait et le devine, comme d&rsquo;un ph\u00e9nom\u00e8ne \u00e9chappant aux circonstances et aux \u00e9v\u00e9nements, un ph\u00e9nom\u00e8ne qui \u00e9chappe \u00e0 la logique de notre destin parce qu&rsquo;elle en est la cr\u00e9atrice, parce qu&rsquo;elle se trouve en-dehors et dicte sa logique \u00e0 notre destin. Elle \u00e9chappe donc \u00e0 notre histoire que l&rsquo;esprit commun croit continuer \u00e0 vivre, pour tenir la place de la m\u00e9tahistoire. Soyons scientifiques et empruntons leurs formules : \u00ab\u00a0tout se passe comme si\u00a0\u00bb une force d&rsquo;En-Haut lui avait d\u00e9l\u00e9gu\u00e9 ce pouvoir et cette fonction, sinon sa l\u00e9gitimit\u00e9 cosmique.<\/p>\n<\/p>\n<p><p>La GrandeCrise ne d\u00e9pend pas d&rsquo;une crise, ni des multiples crises que nous nommons \u00ab\u00a0subcrises\u00a0\u00bb, qui \u00e9clatent  un peu partout et  qui jamais ne se r\u00e9solvent. Les moindres incidents, les r\u00e9flexes les plus banals, les r\u00e9flexes les plus primaires sont aussit\u00f4t exploit\u00e9s dans le sens voulu par la GrandeCrise. Prenez Boris Johnson du temps de sa direction brutale du pays, &ndash; entretemps et apr\u00e8s son d\u00e9part de Downing Street, mis <a href=\"https:\/\/sputnikglobe.com\/20250909\/boris-johnson-used-his-political-influence-for-personal-gain-after-resigning-1122753722.html\">en f\u00e2cheuse posture<\/a> pour de juteux incidents de corruption avec de tr\u00e8s-vilaines fr\u00e9quentations selon le simulacre am\u00e9ricaniste-occidentaliste (le V\u00e9n\u00e9zu\u00e9lien Maduro, notamment, pour $270 000) ; souvenez-vous de sa brutalit\u00e9 et de sa grossi\u00e8ret\u00e9, en mars-avril 2022, pour emp\u00eacher un accord de paix entre l&rsquo;Ukraine et la Russie. Vous trouvez l\u00e0 la cause de la circonstance qui a fait de la guerre en Ukraine un formidable d\u00e9tonateur au service de la GrandeCrise (et de la Russie, cette fois comme tant d&rsquo;autres plac\u00e9e dans le sens qui nous importe).<\/p>\n<\/p>\n<p><p>Ce cher <em>old <\/em>Boris a agi avec une brutalit\u00e9 toute britannique, moyen du temps de l&#8217;empire de la puissance supr\u00e9maciste anglo-saxonne, et aujourd&rsquo;hui devenu son tombeau \u00e0 cause justement du comportement de ce Premier ministre qui se trompe d&rsquo;\u00e9poque. Son acte a fait de la guerre en Ukraine, qui pouvait \u00eatre ais\u00e9ment contenue localement et ne pas bouleverser l&rsquo;ordre du monde m\u00eame si la Russie y gagnait, un \u00e9v\u00e9nement mondial qui acc\u00e9l\u00e8re au-del\u00e0 de toute mod\u00e9ration le d\u00e9cha&icirc;nement crisique en cours en donnant \u00e0 cette m\u00eame Russie la puissance de levier de bouleverser le monde (&laquo; <em>Donnez-moi un point fixe et un levier et je soul\u00e8verai la Terre<\/em> &raquo;, nous dit Archim\u00e8de)&#8230;<\/p>\n<\/p>\n<p><p>En effet, quels r\u00e9sultats ?<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>La Russie reste cependant un cas particulier. D&rsquo;une &laquo; op\u00e9ration courte &raquo; pr\u00e9vue, le conflit est devenu la plus grande guerre en Europe depuis 1945. Cela a d\u00e9pass\u00e9 Moscou, mais paradoxalement, cela l&rsquo;a aussi renforc\u00e9e : la Russie tient bon &ndash; et cela seul modifie la perception mondiale. <\/em>&raquo; (Elena Fritz)<\/p>\n<\/p>\n<p><p>&laquo;<em> Il est de plus en plus clair que la Chine et la Russie souhaitent fa\u00e7onner un monde conforme \u00e0 leur mod\u00e8le autoritaire <\/em>&raquo; (&lsquo;National Defense Strategy&rsquo; du Pentagone)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ce n&rsquo;est qu&rsquo;un exemple parmi tant d&rsquo;autres, mais Boris Johnson le d\u00e9montre magnifiquement. Ce que je veux montrer ici n&rsquo;est pas tant l'\u00a0\u00bb<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Effet_papillon\">effet papillon<\/a>\u00a0\u00bb (vous savez, un infime battement d&rsquo;aile d&rsquo;un papillon en Australie provoquant un ouragan gigantesque en Floride malgr\u00e9 les hurlements de fureur de Trump) mais plut\u00f4t le ph\u00e9nom\u00e8ne de ce qu&rsquo;on pourrait nommer \u00ab\u00a0la r\u00e8gle de l&rsquo;unicit\u00e9 des effets crisiques\u00a0\u00bb, montrant que toutes les occasions, y compris les comportements de brute de Johnson, sont syst\u00e9matiquement utilis\u00e9es selon la logique impos\u00e9e par la GrandeCrise pour multiplier et acc\u00e9l\u00e9rer l&rsquo;encha&icirc;nement crisique.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p><strong><em>Note de PhGBis<\/em><\/strong><em> : &laquo; Par qui ces occasions sont-elles utilis\u00e9es ? Qui cherche donc \u00e0 conduire \u00e0 son terme la GrandeCrise ? On ne r\u00e9pond pas \u00e0 ces questions indiscr\u00e8tes, sinon en excluant toute organisation et intervention humaines organis\u00e9es. Notez simplement, cela a d\u00e9j\u00e0 \u00e9t\u00e9 \u00e9voqu\u00e9, combien de fois d\u00e9j\u00e0 sur un ton feutr\u00e9, puis r\u00e9cemment sur un ton pas si feutr\u00e9 que \u00e7a. Par exemple, le <a href=\"https:\/\/www.dedefensa.org\/article\/la-narrative-concerne-desormais-le-divin\">18 ao&ucirc;t 2025<\/a> :<\/em><\/p>\n<\/p>\n<p><p>&laquo; <em>La narrative concerne d\u00e9sormais le divin&#8230; Ce dont nous parlons d\u00e9sormais a la r\u00e9sonance du divin et de sa r\u00e9volution cosmique<\/em>. &raquo; (&lsquo;<em>dedefensa.org<\/em>&lsquo;)<\/p>\n<\/p>\n<p><p>&laquo; <em>En d&rsquo;autres termes, la phase terminale que nous vivons actuellement ne peut s&rsquo;expliquer uniquement dans une perspective historico-politique, mais s&rsquo;inscrit dans un cycle cosmique. Elle touche non seulement les cordes intimes de l&rsquo;humain, mais aussi celles du divin.<\/em>.. &raquo; (<em>Michele<\/em>&lsquo; du &lsquo;<em>Blocco Studentesco<\/em>&lsquo;)<\/p>\n<\/p>\n<\/blockquote>\n<p><p> L'\u00a0\u00bbeffet papillon\u00a0\u00bb indique un rapport d&rsquo;amplification colossal, avec un parcours en droite ligne montante ; le geste de Johnson (qui est infiniment plus important en intensit\u00e9 et en effets directs qu&rsquo;un battement d&rsquo;aile d&rsquo;un papillon) montre la fatalit\u00e9 dynamique selon laquelle, dans un cadre donn\u00e9 qui implique une n\u00e9cessit\u00e9 de course pouvant prendre une forme elliptique (Johnson, outre sa corruption, repr\u00e9sente l&rsquo;Angleterre qui se retrouve d\u00e9vast\u00e9e  par la crise ukrainienne en m\u00eame temps qu&rsquo;il est d\u00e9nonc\u00e9 comme corrompu), toute initiative va dans le m\u00eame sens de notre destin crisique de renforcement de la GrandeCrise<\/p>\n<\/p>\n<p><p>Par cons\u00e9quent, tout est li\u00e9 dans le destin de la GrandeCrise, auquel nous ne pouvons \u00e9chapper en aucune fa\u00e7on&#8230;<\/p>\n<\/p>\n<p><p>Observez tous les \u00e9v\u00e9nements : tous sont gros d&rsquo;une crise, et s&rsquo;ils en accouchent, c&rsquo;est-\u00e0-dire quasiment \u00e0 chaque occasion apr\u00e8s tout, il leur est impossible de s&rsquo;en d\u00e9barrasser (combien de crises r\u00e9solues de fa\u00e7on satisfaisante, jusqu&rsquo;\u00e0 la stabilit\u00e9, disons depuis le 11 septembre, ou, mieux encore, depuis 1981991 ?). On ne jette pas le b\u00e9b\u00e9 avec l&rsquo;eau du bain pour clore une crise, on garde l&rsquo;eau du bain parce qu&rsquo;on est cupide et qu&rsquo;on refuse le compromis, et on d\u00e9couvre qu&rsquo;il est impossible de se d\u00e9barrasser du b\u00e9b\u00e9 (la crise).<\/p>\n<\/p>\n<p><p>Cette r\u00e8gle terrible vaut bien entendu pour tous les ennemis objectifs de la GrandeCrise, ceux qui combattent avec une vaillance que seule la stupidit\u00e9 et la corruption suscitent ; en gros, tous les vaillants archers de l&rsquo;am\u00e9ricanisme-occidentaliste. Ceux qui s&rsquo;en sortent avec les honneurs et quelques projets ambitieux sont ceux qui, <em>volens nolens <\/em>(et plut\u00f4t<em> nolens<\/em>, hein !), travaillent dans le sens de la GrandeCrise.<\/p>\n<\/p>\n<p><p>Nous savons parfaitement o&ugrave; notre destin se dirige et nous ne pouvons en aucun cas faire autre chose que le suivre. Mais il est entendu que vous pouvez d\u00e9cider cela en toute libert\u00e9, selon votre libre-arbitre si vous voulez.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le torrent irr\u00e9fragable de la GrandeCrise 9 septembre 2025 (16H20) &ndash; Je parle de la GrandeCrise, on le sait et le devine, comme d&rsquo;un ph\u00e9nom\u00e8ne \u00e9chappant aux circonstances et aux \u00e9v\u00e9nements, un ph\u00e9nom\u00e8ne qui \u00e9chappe \u00e0 la logique de notre destin parce qu&rsquo;elle en est la cr\u00e9atrice, parce qu&rsquo;elle se trouve en-dehors et dicte sa&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[2757,2604,14506,2651,13748,14507],"class_list":["post-81668","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-crises","tag-des","tag-divin","tag-du","tag-interventioin","tag-linevitabilite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81668"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81668\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}