{"id":81717,"date":"2025-10-21T15:25:04","date_gmt":"2025-10-21T15:25:04","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2025\/10\/21\/le-new-deal-brun-partie-ii\/"},"modified":"2025-10-21T15:25:04","modified_gmt":"2025-10-21T15:25:04","slug":"le-new-deal-brun-partie-ii","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2025\/10\/21\/le-new-deal-brun-partie-ii\/","title":{"rendered":"Le New Deal brun, partie II"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><strong>Le New Deal brun, partie II<\/strong><\/h2>\n<\/p>\n<p><p>Lorsque Trump a d\u00e9clar\u00e9 devant l&rsquo;ONU : <em>&laquo; Si vous ne vous \u00e9loignez pas de cette arnaque verte, votre pays va faire faillite &raquo;<\/em>, il mentait bien s&ucirc;r. Si <em>&laquo; votre pays &raquo;<\/em> fait partie de l&rsquo;UE, il n&rsquo;y a pas moyen d&rsquo;\u00e9chapper \u00e0 <em>&laquo; cette arnaque verte &raquo;<\/em> : l&rsquo;argent a d\u00e9j\u00e0 \u00e9t\u00e9 mal d\u00e9pens\u00e9 et les infrastructures \u00e9nerg\u00e9tiques ont d\u00e9j\u00e0 \u00e9t\u00e9 compromises. La Russie a d\u00e9j\u00e0 renonc\u00e9 au march\u00e9 \u00e9nerg\u00e9tique europ\u00e9en et r\u00e9orient\u00e9 ses exportations \u00e9nerg\u00e9tiques vers l&rsquo;Est. Pour l&rsquo;UE, une d\u00e9sindustrialisation rapide est d\u00e9sormais in\u00e9vitable. La d\u00e9claration de Trump peut donc \u00eatre r\u00e9sum\u00e9e ainsi : <em>&laquo; Votre pays va faire faillite &raquo;<\/em>.<\/p>\n<\/p>\n<p><p>Mais ce n&rsquo;est pas ce que les dirigeants europ\u00e9ens voulaient entendre. Admettre que Trump a raison reviendrait \u00e0 d\u00e9missionner volontairement de leurs fonctions, et ce n&rsquo;est pas ce qu&rsquo;ils avaient en t\u00eate. Au lieu de d\u00e9missionner (ce qui aurait \u00e9t\u00e9 honorable de leur part), ils ont pr\u00e9f\u00e9r\u00e9 donner le feu vert \u00e0 une nouvelle arnaque, plus grande et plus efficace, que j&rsquo;appellerai le New Deal Brun.<\/p>\n<\/p>\n<p><p>Contrairement \u00e0 la couleur verte, la couleur brune est riche en connotations n\u00e9gatives. C&rsquo;est la couleur par d\u00e9faut des choses mortes : les feuilles vertes prennent une multitude de belles couleurs lorsqu&rsquo;elles se fanent au premier gel, puis tombent doucement au sol et, apr\u00e8s quelques pluies d&rsquo;automne, deviennent invariablement brunes. Le brun \u00e9tait \u00e9galement la couleur des chemises port\u00e9es par les <em>chemises brunes<\/em>, la branche paramilitaire (Sturmabteilung) du parti nazi allemand, dont le comportement violent et odieux a contribu\u00e9 \u00e0 l&rsquo;ascension d&rsquo;Hitler au pouvoir. Ainsi, le brun est \u00e9galement la couleur des nations en d\u00e9composition. C&rsquo;est aussi la couleur des excr\u00e9ments, gr\u00e2ce \u00e0 l&rsquo;effet pigmentaire de la bilirubine, un d\u00e9chet issu de la d\u00e9gradation de l&rsquo;h\u00e8me, provenant des vieux globules rouges, qui est produit dans le foie et excr\u00e9t\u00e9. La bilirubine est ce qui donne leur couleur \u00e0 la bile et aux mati\u00e8res f\u00e9cales. Enfin, c&rsquo;est la couleur de peau des populations humaines indig\u00e8nes des pays tropicaux ; ici, ce sont les racistes qui lui donnent sa connotation n\u00e9gative.<\/p>\n<\/p>\n<p><p>Je n&rsquo;ai pas l&rsquo;intention de peindre tout ce qui est brun avec un seul pinceau ; apr\u00e8s tout, certaines choses brunes sont tout \u00e0 fait acceptables. Il y a bien s&ucirc;r le chocolat et le sucre brun, qui n&rsquo;ont pas besoin d&rsquo;\u00eatre vant\u00e9s. Il y a la couleur brune de l&rsquo;eau tannique <em>&laquo; forte &raquo;<\/em>, appr\u00e9ci\u00e9e des marins d&rsquo;autrefois. Pr\u00e9lev\u00e9e dans les estuaires, au-dessus du niveau des mar\u00e9es, des rivi\u00e8res qui drainent les for\u00eats et les mar\u00e9cages, et stock\u00e9e dans des tonneaux sur les ponts des voiliers, l&rsquo;eau <em>&laquo; forte &raquo;<\/em> mettait beaucoup plus de temps \u00e0 devenir <em>&laquo; vive &raquo;<\/em> (c&rsquo;est-\u00e0-dire verte). Dans ce cas, contrairement \u00e0 ce que l&rsquo;on pourrait croire, l&rsquo;eau brune \u00e9tait potable (bien qu&rsquo;am\u00e8re), tandis que l&rsquo;eau verte provoquait \u00e0 coup s&ucirc;r des diarrh\u00e9es. Enfin, que feraient les architectes, les d\u00e9corateurs d&rsquo;int\u00e9rieur, les cr\u00e9ateurs de mode, l&rsquo;\u00e9quipe de maquillage de Trump et divers autres artistes et artisans sans les diff\u00e9rentes nuances de beige, de brun clair, de sienne, d&rsquo;ombre, de taupe et de fauve ?<\/p>\n<\/p>\n<p><p>Le 12 octobre 2025, <a href=\"https:\/\/boosty.to\/cluborlov\/posts\/e49e008b-bc79-43d9-baae-fd14e5f49d8b\">Club Orlov<\/a> &ndash; Traduction du &lsquo;<em><a href=\"https:\/\/lesakerfrancophone.fr\/le-new-deal-brun-partie-ii\">Sakerfrancophone<\/a><\/em>&lsquo;<\/p>\n<\/p>\n<p><\/p>\n<p><p><em>Note du Saker Francophone<\/em><\/p>\n<\/p>\n<p><p><em>Depuis quelques temps, des gens ind\u00e9licats retraduisent \u00ab\u00a0mal\u00a0\u00bb en anglais nos propres traductions sans l&rsquo;autorisation de l&rsquo;auteur qui vit de ses publications. Dmitry Orlov nous faisait l&rsquo;amiti\u00e9 depuis toutes ses ann\u00e9es de nous laisser publier les traductions fran\u00e7aises de ses articles, m\u00eame ceux payant pour les anglophones. Dans ces nouvelles conditions, en accord avec l&rsquo;auteur, on vous propose la 1ere partie de l&rsquo;article ici. Vous pouvez lire la suite en fran\u00e7ais <a href=\"https:\/\/boosty.to\/cluborlov\/posts\/967100dd-569e-4780-a2de-9ece1af71b15\">derri\u00e8re ce lien<\/a> en vous abonnant au site <a href=\"https:\/\/boosty.to\/cluborlov\">Boosty<\/a> de Dmitry Orlov.<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le New Deal brun, partie II Lorsque Trump a d\u00e9clar\u00e9 devant l&rsquo;ONU : &laquo; Si vous ne vous \u00e9loignez pas de cette arnaque verte, votre pays va faire faillite &raquo;, il mentait bien s&ucirc;r. Si &laquo; votre pays &raquo; fait partie de l&rsquo;UE, il n&rsquo;y a pas moyen d&rsquo;\u00e9chapper \u00e0 &laquo; cette arnaque verte &raquo;&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[3392,3228,3478,2668,2639],"class_list":["post-81717","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-dimitri-orlov-1","tag-climatique","tag-crise","tag-onu","tag-orlov","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=81717"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/81717\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=81717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=81717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=81717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}